{"text_format":"1","workbook":"xlsx","n_sheets":9,"sheets":["COVER PAGE","General Instructions","ASCII","1. Leverage Ratio","2. Derivative Exposures","3.Off-Balance Sheet Exposures","Signature","Validations","Institution_Codes"],"not_rendered":{"charts":0,"images":1,"macros":1,"external_links":8,"defined_names":886,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"COVER PAGE","index":0,"n_rows":13,"n_cols":6,"rows_kept":13,"cut":false,"hidden":false,"merged":[[6,2,6,9],[1,2,1,9],[2,2,2,9],[3,2,3,9],[4,2,4,9],[5,2,5,9],[11,4,11,7],[12,4,12,7],[7,2,7,9],[8,2,8,4],[8,5,8,6],[8,7,8,9],[9,5,9,6],[10,2,10,9]]}
[]
[null,null,"CENTRAL BANK OF TRINIDAD AND TOBAGO "]
[null,null,"V1.1"]
[null,null,"CB100LR - LEVERAGE RATIO RETURN"]
[null,null,"Date Issued : 23/08/2024"]
[null,null,"FOR "]
[null,null,"Select Institution"]
[null,null,"For the Month Ended:"]
[null,null,"Month ",null,null,"July"]
[null,null,null,null,"Year",2023]
[null,null,"Date Submitted:"]
[null,null,null,null,"07/28/2023"]
[null,null,null,null,"Type mm/dd/yyyy"]

{"sheet":"General Instructions","index":1,"n_rows":26,"n_cols":2,"rows_kept":26,"cut":false,"hidden":false,"merged":[]}
[null,"LEVERAGE RATIO RETURN"]
[null,"Please use the Leverage Ratio instructions to complete the return using the link below. "]
[null,"CB100LR Instructions"]
[]
[null,"GENERAL INSTRUCTIONS"]
[1,"Do not amend the structure/format."]
[2,"Do not remove the password protection."]
[3,"Do not manipulate the formulas."]
[4,"Complete Cover Page before submission. \nInstitution, reporting month and date submitted must be populated. "]
[5,"No blank cells.  All cells must be populated with zero where there is no data."]
[6,"Do not use text."]
[7,"Do not use symbols in cells (<, >, commas, full stops, apostrophe, tilde etc.)."]
[8,"Ensure when links are broken the files are checked for text references which have to be deleted/amended (#Ref, FALSE! etc.) prior to submission. "]
[9,"The file format should be Microsoft Excel with the extension \".xlsx\"."]
[]
[null,"FILE NAMING FOR SUBMISSION"]
[10,"Use the file name structure \"Institution Code_CB100LR_V1.1_MMMYYYY\". "]
[11,"Resubmissions must have the same file name structure as listed in 10 above."]
[12,"The file name structure above is applicable to monthly and quarterly submissions."]
[]
[null,"CONVERTING TO .XLSX AND SAVING FOR SUBMISSION"]
[13,"Select the \"Convert to (.xlsx) and Save\" button on the \"VALIDATIONS\" tab to save the final version for submission.  "]
[14,"Follow the prompts to break all external links and save the return as .xlsx."]
[15,"Please ensure there are no validation errors on the \"VALIDATIONS\" tab after links are broken."]
[16,"Remember to save the file in the recommended naming convention \"Institution Code_CB100LR_V1.1_MMMYYYY\" as per instruction number 10."]
[17,"Once the steps above are completed the submission can be uploaded into GoAnywhere."]

{"sheet":"ASCII","index":2,"n_rows":89,"n_cols":2,"rows_kept":89,"cut":false,"hidden":true,"merged":[]}
["hdr",{"$f":"VLOOKUP('COVER PAGE'!$C$7,Institution_Codes!$A$1:$B$35,2,)","v":"-"}]
[{"$f":"VLOOKUP('COVER PAGE'!F9,Institution_Codes!D2:E13,2,FALSE)","v":7}]
[{"$f":"VLOOKUP('COVER PAGE'!F10,Institution_Codes!H2:I44,2,)","v":23}]
[{"$f":"$B$1&\".CB100LR.1.1.a\"","v":"-.CB100LR.1.1.a"},{"$f":"ROUND('1. Leverage Ratio'!D8,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.1.b\"","v":"-.CB100LR.1.1.b"},{"$f":"ROUND('1. Leverage Ratio'!D9,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.1.c\"","v":"-.CB100LR.1.1.c"},{"$f":"ROUND('1. Leverage Ratio'!D10,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.1.d\"","v":"-.CB100LR.1.1.d"},{"$f":"ROUND('1. Leverage Ratio'!D11,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.1.e\"","v":"-.CB100LR.1.1.e"},{"$f":"ROUND('1. Leverage Ratio'!D12,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.1.f\"","v":"-.CB100LR.1.1.f"},{"$f":"ROUND('1. Leverage Ratio'!D13,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.1.0\"","v":"-.CB100LR.1.1.0"},{"$f":"ROUND('1. Leverage Ratio'!D14,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.1.g\"","v":"-.CB100LR.1.1.g"},{"$f":"ROUND('1. Leverage Ratio'!D15,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.2.d\"","v":"-.CB100LR.1.2.d"},{"$f":"ROUND('1. Leverage Ratio'!D20,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.2.e\"","v":"-.CB100LR.1.2.e"},{"$f":"ROUND('1. Leverage Ratio'!D21,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.2.0\"","v":"-.CB100LR.1.2.0"},{"$f":"ROUND('1. Leverage Ratio'!D22,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.3.a\"","v":"-.CB100LR.1.3.a"},{"$f":"ROUND('1. Leverage Ratio'!D24,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.3.b\"","v":"-.CB100LR.1.3.b"},{"$f":"ROUND('1. Leverage Ratio'!D25,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.3.c\"","v":"-.CB100LR.1.3.c"},{"$f":"ROUND('1. Leverage Ratio'!D26,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.3.d\"","v":"-.CB100LR.1.3.d"},{"$f":"ROUND('1. Leverage Ratio'!D27,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.3.0\"","v":"-.CB100LR.1.3.0"},{"$f":"ROUND('1. Leverage Ratio'!D28,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.4.0\"","v":"-.CB100LR.1.4.0"},{"$f":"ROUND('1. Leverage Ratio'!D34,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.5.0\"","v":"-.CB100LR.1.5.0"},{"$f":"ROUND('1. Leverage Ratio'!D36,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.5.a\"","v":"-.CB100LR.1.5.a"},{"$f":"ROUND('1. Leverage Ratio'!D37,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.5.b\"","v":"-.CB100LR.1.5.b"},{"$f":"ROUND('1. Leverage Ratio'!D38,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.5.c\"","v":"-.CB100LR.1.5.c"},{"$f":"ROUND('1. Leverage Ratio'!D39,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.1.5.d\"","v":"-.CB100LR.1.5.d"},{"$f":"ROUND('1. Leverage Ratio'!D40,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.a.cdc.i\"","v":"-.CB100LR.2.1.a.cdc.i"},{"$f":"ROUND('2. Derivative Exposures'!D4,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.a.cdc.ii\"","v":"-.CB100LR.2.1.a.cdc.ii"},{"$f":"ROUND('2. Derivative Exposures'!D5,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.a.cdc.iii\"","v":"-.CB100LR.2.1.a.cdc.iii"},{"$f":"ROUND('2. Derivative Exposures'!D6,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.a.cdc.iv\"","v":"-.CB100LR.2.1.a.cdc.iv"},{"$f":"ROUND('2. Derivative Exposures'!D7,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.a.fdc.i\"","v":"-.CB100LR.2.1.a.fdc.i"},{"$f":"ROUND('2. Derivative Exposures'!E4,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.a.fdc.ii\"","v":"-.CB100LR.2.1.a.fdc.ii"},{"$f":"ROUND('2. Derivative Exposures'!E5,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.a.fdc.iii\"","v":"-.CB100LR.2.1.a.fdc.iii"},{"$f":"ROUND('2. Derivative Exposures'!E6,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.a.fdc.iv\"","v":"-.CB100LR.2.1.a.fdc.iv"},{"$f":"ROUND('2. Derivative Exposures'!E7,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.a.tc.i\"","v":"-.CB100LR.2.1.a.tc.i"},{"$f":"ROUND('2. Derivative Exposures'!F4,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.a.tc.ii\"","v":"-.CB100LR.2.1.a.tc.ii"},{"$f":"ROUND('2. Derivative Exposures'!F5,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.a.tc.iii\"","v":"-.CB100LR.2.1.a.tc.iii"},{"$f":"ROUND('2. Derivative Exposures'!F6,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.a.tc.iv\"","v":"-.CB100LR.2.1.a.tc.iv"},{"$f":"ROUND('2. Derivative Exposures'!F7,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.b.cdc.i\"","v":"-.CB100LR.2.1.b.cdc.i"},{"$f":"ROUND('2. Derivative Exposures'!D9,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.b.cdc.ii\"","v":"-.CB100LR.2.1.b.cdc.ii"},{"$f":"ROUND('2. Derivative Exposures'!D10,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.b.cdc.iii\"","v":"-.CB100LR.2.1.b.cdc.iii"},{"$f":"ROUND('2. Derivative Exposures'!D11,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.b.cdc.iv\"","v":"-.CB100LR.2.1.b.cdc.iv"},{"$f":"ROUND('2. Derivative Exposures'!D12,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.b.fdc.i\"","v":"-.CB100LR.2.1.b.fdc.i"},{"$f":"ROUND('2. Derivative Exposures'!E9,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.b.fdc.ii\"","v":"-.CB100LR.2.1.b.fdc.ii"},{"$f":"ROUND('2. Derivative Exposures'!E10,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.b.fdc.iii\"","v":"-.CB100LR.2.1.b.fdc.iii"},{"$f":"ROUND('2. Derivative Exposures'!E11,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.b.fdc.iv\"","v":"-.CB100LR.2.1.b.fdc.iv"},{"$f":"ROUND('2. Derivative Exposures'!E12,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.b.tc.i\"","v":"-.CB100LR.2.1.b.tc.i"},{"$f":"ROUND('2. Derivative Exposures'!F9,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.b.tc.ii\"","v":"-.CB100LR.2.1.b.tc.ii"},{"$f":"ROUND('2. Derivative Exposures'!F10,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.b.tc.iii\"","v":"-.CB100LR.2.1.b.tc.iii"},{"$f":"ROUND('2. Derivative Exposures'!F11,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.1.b.tc.iv\"","v":"-.CB100LR.2.1.b.tc.iv"},{"$f":"ROUND('2. Derivative Exposures'!F12,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.2.a.cdc.i\"","v":"-.CB100LR.2.2.a.cdc.i"},{"$f":"ROUND('2. Derivative Exposures'!D16,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.2.a.cdc.ii\"","v":"-.CB100LR.2.2.a.cdc.ii"},{"$f":"ROUND('2. Derivative Exposures'!D18,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.2.a.cdc.iii\"","v":"-.CB100LR.2.2.a.cdc.iii"},{"$f":"ROUND('2. Derivative Exposures'!D19,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.2.2.a.cdc.iv\"","v":"-.CB100LR.2.2.a.cdc.iv"},{"$f":"ROUND('2. Derivative Exposures'!D20,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.a.na\"","v":"-.CB100LR.3.1.a.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C3,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.1.na\"","v":"-.CB100LR.3.1.1.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C4,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.b.na\"","v":"-.CB100LR.3.1.b.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C5,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.c.na\"","v":"-.CB100LR.3.1.c.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C6,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.2.na\"","v":"-.CB100LR.3.1.2.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C7,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.d.na\"","v":"-.CB100LR.3.1.d.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C8,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.e.na\"","v":"-.CB100LR.3.1.e.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C9,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.f.na\"","v":"-.CB100LR.3.1.f.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C10,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.3.na\"","v":"-.CB100LR.3.1.3.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C11,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.g.na\"","v":"-.CB100LR.3.1.g.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C12,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.h.na\"","v":"-.CB100LR.3.1.h.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C13,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.i.na\"","v":"-.CB100LR.3.1.i.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C14,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.j.na\"","v":"-.CB100LR.3.1.j.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C15,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.k.na\"","v":"-.CB100LR.3.1.k.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C16,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.l.na\"","v":"-.CB100LR.3.1.l.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C17,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.m.na\"","v":"-.CB100LR.3.1.m.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C18,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.4.na\"","v":"-.CB100LR.3.1.4.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C19,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.5.na\"","v":"-.CB100LR.3.1.5.na"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!C20,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.a.exp\"","v":"-.CB100LR.3.1.a.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E3,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.1.exp\"","v":"-.CB100LR.3.1.1.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E4,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.b.exp\"","v":"-.CB100LR.3.1.b.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E5,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.c.exp\"","v":"-.CB100LR.3.1.c.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E6,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.2.exp\"","v":"-.CB100LR.3.1.2.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E7,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.d.exp\"","v":"-.CB100LR.3.1.d.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E8,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.e.exp\"","v":"-.CB100LR.3.1.e.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E9,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.f.exp\"","v":"-.CB100LR.3.1.f.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E10,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.3.exp\"","v":"-.CB100LR.3.1.3.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E11,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.g.exp\"","v":"-.CB100LR.3.1.g.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E12,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.h.exp\"","v":"-.CB100LR.3.1.h.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E13,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.i.exp\"","v":"-.CB100LR.3.1.i.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E14,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.j.exp\"","v":"-.CB100LR.3.1.j.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E15,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.k.exp\"","v":"-.CB100LR.3.1.k.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E16,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.l.exp\"","v":"-.CB100LR.3.1.l.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E17,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.m.exp\"","v":"-.CB100LR.3.1.m.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E18,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.4.exp\"","v":"-.CB100LR.3.1.4.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E19,5)","v":0}]
[{"$f":"$B$1&\".CB100LR.3.1.5.exp\"","v":"-.CB100LR.3.1.5.exp"},{"$f":"ROUND('3.Off-Balance Sheet Exposures'!E20,5)","v":0}]

{"sheet":"1. Leverage Ratio","index":3,"n_rows":40,"n_cols":5,"rows_kept":40,"cut":false,"hidden":false,"merged":[[0,0,0,3],[22,1,22,2],[27,1,27,2],[28,1,28,2],[33,1,33,2],[3,0,3,3],[2,0,2,3],[1,0,1,3],[21,1,21,2],[4,0,4,3],[5,0,5,2],[6,1,6,2],[13,1,13,2],[15,1,15,2],[39,1,39,2],[35,1,35,2],[34,1,34,2],[36,1,36,2],[37,1,37,2],[38,1,38,2]]}
["LEVERAGE RATIO CALCULATION"]
[{"$f":"'COVER PAGE'!C7","v":"Select Institution"}]
[{"$f":"'COVER PAGE'!$F$9&\" - \"&'COVER PAGE'!$F$10","v":"July - 2023"}]
[{"$f":"RIGHT(CELL(\"filename\",E1),LEN(CELL(\"filename\",E1))-SEARCH(\"]\",CELL(\"filename\",E1)))","v":"1. Leverage Ratio"}]
["SECTION A-EXPOSURE MEASURE"]
[null,null,null,"TT$ ('000)\n"]
[1,"On-Balance Sheet Assets"]
["a",null,"On-Balance Sheet Assets - Gross",0]
["b","Less","Specific Provisions  ",0]
["c","Less","Accounting Valuation Adjustments",0]
["d",null,"On-Balance Sheet Assets - Net",{"$f":"D8-SUM(D9:D10)","v":0}]
["e","Less:","Balance Sheet Assets deducted from Tier 1 capital",0]
["f","Less:","Receivables in respect of cash variation margin provided in derivatives transactions",0]
[0,"TOTAL On-Balance Sheet Exposure",null,{"$f":"D11-D12-D13","v":0},"A"]
["g","Memo item: ","Adjustment for SFT Sales Accounting Transactions",0]
[2,"Derivative Exposures"]
["a",null,"Derivatives not covered by an eligible bilateral netting contract",{"$f":"'2. Derivative Exposures'!F7","v":0},"AA from 2. Derivatives Exposures"]
["b",null,"Derivatives covered by an eligible bilateral netting contract",{"$f":"'2. Derivative Exposures'!F12","v":0},"BB from 2. Derivatives Exposures"]
["c",null,"Effective notional exposure for written credit derivatives",{"$f":"'2. Derivative Exposures'!D20","v":0},"CC from 2. Derivatives Exposures"]
["d","Less:","RC of exempted leg of client-cleared trade exposure",0]
["e","Less:","Potential future exposures of exempted leg of client-cleared trade exposure",0]
[0,"TOTAL Derivative Exposures",null,{"$f":"SUM(D17:D19)-SUM(D20:D21)","v":0},"B"]
[3,"Securities Financing Transactions (SFTs) "]
["a",null,"Bank as principal: Gross SFT assets, after adjusting for sales accounting transactions and other required adjustments",0]
["b",null,"Bank as principal: Counterparty credit risk exposure for SFT assets, including sales accounting transactions",0]
["c",null,"Bank acting as agent: SFT Exposures - CCR exposure",0]
["d",null,"Bank acting as agent: SFT Exposures amount of security or cash for which bank is responsible in excess of the difference",0]
[0,"TOTAL SFTs Exposures",null,{"$f":"SUM(D24:D27)","v":0},"C"]
[4,"Off-Balance Sheet Exposures"]
["a",null,"Exposures with a 10% CCF, after the CCF",{"$f":"'3.Off-Balance Sheet Exposures'!E4","v":0},"DD from 3. Off-Balance Sheet"]
["b",null,"Exposures with a 20% CCF, after the CCF",{"$f":"'3.Off-Balance Sheet Exposures'!E7","v":0},"EE from 3. Off-Balance Sheet"]
["c",null,"Exposures with a 50% CCF, after the CCF",{"$f":"'3.Off-Balance Sheet Exposures'!E11","v":0},"FF from 3. Off-Balance Sheet"]
["d",null,"Exposures with a 100% CCF, after the CCF",{"$f":"'3.Off-Balance Sheet Exposures'!E19","v":0},"GG from 3. Off-Balance Sheet"]
[0,"TOTAL Off-Balance Sheet Exposures",null,{"$f":"SUM(D30:D33)","v":0},"D"]
[5,"SECTION B-LEVERAGE RATIO CALCULATION"]
[0,"TOTAL EXPOSURE MEASURE",null,{"$f":"(D14+D22+D28+D34)","v":0},"F=(A+B+C+D)"]
["a","TIER 1 CAPITAL before deductions",null,0]
["b","Less: Deductions from Tier 1",null,0]
["c","Tier 1 CAPITAL after deductions",null,{"$f":"D37-D38","v":0},"G"]
["d","LEVERAGE RATIO %",null,{"$f":"IF(OR($D$36=0,$D$39=0),\"0\",$D$39/$D$36)","v":"0"}]

{"sheet":"2. Derivative Exposures","index":4,"n_rows":20,"n_cols":7,"rows_kept":20,"cut":false,"hidden":false,"merged":[[0,0,0,2]]}
[{"$f":"RIGHT(CELL(\"filename\",A1),LEN(CELL(\"filename\",A1))-SEARCH(\"]\",CELL(\"filename\",A1)))","v":"2. Derivative Exposures"}]
["1. Financial and credit derivatives",null,null,"Credit Derivative Contracts\nTT$ ('000)","Financial Derivative Contracts\nTT$ ('000)","Total Contracts \nTT$ ('000)"]
[null,"(a) Single derivative exposures not covered by an eligible netting contract"]
[null,null,"(i) Replacement cost",0,0,{"$f":"D4+E4","v":0}]
[null,null,"(ii) Notional amounts ",0,0,{"$f":"D5+E5","v":0}]
[null,null,"(iii) Potential future exposures",0,0,{"$f":"D6+E6","v":0}]
[null,null,"(iv) Single derivative exposure",{"$f":"D4+D6","v":0},{"$f":"E4+E6","v":0},{"$f":"F4+F6","v":0},"AA"]
[null,"(b) Derivative exposures covered by an eligible netting contract "]
[null,null,"(i) Replacement cost",0,0,{"$f":"D9+E9","v":0}]
[null,null,"(ii) Notional amounts",0,0,{"$f":"D10+E10","v":0}]
[null,null,"(iii) Potential future exposures",0,0,{"$f":"D11+E11","v":0}]
[null,null,"(iv) Exposure for netted derivatives",{"$f":"D9+D11","v":0},{"$f":"E9+E11","v":0},{"$f":"F9+F11","v":0},"BB"]
[]
["2. Additional information and treatment for credit derivatives",null,null,"Credit Derivative Contracts\nTT$ ('000)"]
[null,"(a) Cash instrument equivalency"]
[null,null,"(i) Total written credit derivatives - notional",0]
[null,null,"Eligible offsets:"]
[null,null,"(ii) Fair value adjustment to Tier 1",0]
[null,null,"(iii) Eligible purchased credit derivatives",0]
[null,null,"(iv) Net effective notional exposure for written credit derivative",{"$f":"D16-D18-D19","v":0},"CC"]

{"sheet":"3.Off-Balance Sheet Exposures","index":5,"n_rows":34,"n_cols":10,"rows_kept":34,"cut":false,"hidden":false,"merged":[[21,2,21,4],[0,0,0,2]]}
[{"$f":"RIGHT(CELL(\"filename\",A1),LEN(CELL(\"filename\",A1))-SEARCH(\"]\",CELL(\"filename\",A1)))","v":"3.Off-Balance Sheet Exposures"}]
[1,"Off-Balance Sheet Items","Notional Amount\nTT$ ('000)","Credit Conversion Factor (CCF)","Exposure after CCF\nTT$ ('000)"]
["a","Unconditionally cancellable commitments, including eligible servicer cash facilities - 10% CCF",0,0.1,{"$f":"C3*D3","v":0}]
[1,"Exposures with a 10% CCF",{"$f":"C3","v":0},null,{"$f":"E3","v":0},"DD"]
["b","Commitments with an original maturity of one year or less - 20% CCF ",0,0.2,{"$f":"C5*D5","v":0}]
["c","Short-term self-liquidating trade letters of credit - 20% CCF",0,0.2,{"$f":"C6*D6","v":0}]
[2,"Exposures with a 20% CCF",{"$f":"SUM(C5:C6)","v":0},null,{"$f":"SUM(E5:E6)","v":0},"EE"]
["d","Commitments with an original maturity over one year  - 50% CCF ",0,0.5,0]
["e","Transaction-related contingent items - 50% CCF",0,0.5,0]
["f","NIFs and RUFs - 50% CCF",0,0.5,0]
[3,"Exposures with a 50% CCF",{"$f":"SUM(C8:C10)","v":0},null,{"$f":"SUM(E8:E10)","v":0},"FF"]
["g","Non-eligible servicer cash advance facilities - 100% CCF",0,1,0]
["h","Securitization liquidity facilities - 100% CCF ",0,1,0]
["i","Other off balance sheet securitization exposures - 100% CCF",0,1,0]
["j","Direct credit substitutes - 100% CCF",0,1,0]
["k","Forward asset purchases - 100% CCF",0,1,0]
["l","Forward deposits - 100% CCF",0,1,0]
["m","Partly paid shares and securities - 100% CCF",0,1,0]
[4,"Exposures with a 100% CCF",{"$f":"SUM(C12:C18)","v":0},null,{"$f":"SUM(E12:E18)","v":0},"GG"]
[5,"Total Off-Balance Sheet Exposures",{"$f":"C4+C7+C11+C19","v":0},null,{"$f":"E4+E7+E11+E19","v":0},"HH"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,null,null,null,null,null,null,null,null," "]

{"sheet":"Signature","index":6,"n_rows":31,"n_cols":4,"rows_kept":31,"cut":false,"hidden":false,"merged":[]}
[]
[]
[]
[]
[]
[null,"Name of Person Completing Form ",null,"Signature of Person Completing Form "]
[null,"(Block Letters)"]
[]
[]
[]
[]
[null,"Name of Authorised Official ",null,"Signature of Authorised Official "]
[null,"(Block Letters)"]
[]
[]
[]
[]
[null,"Position/Office Held ",null,"Date"]
[null,"(Place Company Stamp)"]
[]
[]
[null,"I hereby certify that data submitted in the e-copy submission are the exact values in the hard-copy return for this period."]
[]
[]
[null,"Name of Authorised Official "]
[]
[]
[null,"Position/Office Held "]
[]
[]
[null,"Date"]

{"sheet":"Validations","index":7,"n_rows":52,"n_cols":8,"rows_kept":52,"cut":false,"hidden":false,"merged":[]}
["LEVERAGE RATIO REPORT - BASEL III",null,null,null,null,"FALSE COUNT","Date Check",{"$f":"(TEXT(MID(RIGHT(MID(CELL(\"filename\",'COVER PAGE'!A1),FIND(\"[\",CELL(\"filename\",'COVER PAGE'!A1))+1,FIND(\"]\", CELL(\"filename\",'COVER PAGE'!A1))-FIND(\"[\",CELL(\"filename\",'COVER PAGE'!A1))-1),LEN(MID(CELL(\"filename\",'COVER PAGE'!A1),FIND(\"[\",CELL(\"filename\",'COVER PAGE'!A1))+1,FIND(\"]\", CELL(\"filename\",'COVER PAGE'!A1))-FIND(\"[\",CELL(\"filename\",'COVER PAGE'!A1))-1))-FIND(\"~\",SUBSTITUTE(MID(CELL(\"filename\",'COVER PAGE'!A1),FIND(\"[\",CELL(\"filename\",'COVER PAGE'!A1))+1,FIND(\"]\", CELL(\"filename\",'COVER PAGE'!A1))-FIND(\"[\",CELL(\"filename\",'COVER PAGE'!A1))-1),\"_\",\"~\",3))),1,7),\"yyyy-MM-dd\"))=(TEXT(TEXT(DATE('COVER PAGE'!F10,MONTH(DATEVALUE('COVER PAGE'!F9 & 1)),\"1\"),\"MMM-YYYY\"),\"yyyy-MM-dd\"))","v":false}]
["Set of rules ID/Description","Rule type","Text rule","Description","Rule ID",{"$f":"COUNTIF(F4:F52,FALSE) +COUNTIF($H$1,FALSE)","v":1}]
["Schedule 1"]
["Validate On-balance sheet assets - Net","In-schedule","S1.DP01-(S1.DP02+S1.DP03)=S1.DP04","1. Leverage Ratio'!D8-('1. Leverage Ratio'!D9+'1. Leverage Ratio'!D10)='1. Leverage Ratio'!D11",1,{"$f":"IF('1. Leverage Ratio'!D8-('1. Leverage Ratio'!D9+'1. Leverage Ratio'!D10)='1. Leverage Ratio'!D11,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Total on-balance sheet exposure","In-schedule","S1.DP04-(S1.DP05+S1.DP06)=S1.DP07","1. Leverage Ratio'!D11-'1. Leverage Ratio'!D12-'1. Leverage Ratio'!D13='1. Leverage Ratio'!D14",{"$f":"E4+1","v":2},{"$f":"IF('1. Leverage Ratio'!D11-'1. Leverage Ratio'!D12-'1. Leverage Ratio'!D13='1. Leverage Ratio'!D14,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Derivatives not covered by an eligible bilateral netting contract","Cross-schedule","S1.DP08=S2.DP24","1. Leverage Ratio'!D17='2. Derivative Exposures'!F7",{"$f":"E5+1","v":3},{"$f":"IF('1. Leverage Ratio'!D17='2. Derivative Exposures'!F7,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Derivatives covered by an eligible bilateral netting contract","Cross-schedule","S1.DP09=S2.DP28","1. Leverage Ratio'!D18='2. Derivative Exposures'!F12",{"$f":"E6+1","v":4},{"$f":"IF('1. Leverage Ratio'!D18='2. Derivative Exposures'!F12,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Effective notional exposure for written credit derivatives","Cross-schedule","S1.DP10=S2.DP08","1. Leverage Ratio'!D19='2. Derivative Exposures'!D20",{"$f":"E7+1","v":5},{"$f":"IF('1. Leverage Ratio'!D19='2. Derivative Exposures'!D20,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Total Derivative Exposures","In-schedule","SUM(S1.DP08:S1.DP10)-SUM(S1.DP11:S1.DP12)=S1.DP13","SUM('1. Leverage Ratio'!D17:D19)-SUM('1. Leverage Ratio'!D20:D21)='1. Leverage Ratio'!D22",{"$f":"E8+1","v":6},{"$f":"IF(SUM('1. Leverage Ratio'!D17:D19)-SUM('1. Leverage Ratio'!D20:D21)='1. Leverage Ratio'!D22,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Total SFTs Exposures","In-schedule","SUM(S1.DP14:S1.DP17)=S1.DP18","SUM('1. Leverage Ratio'!D24:D27)='1. Leverage Ratio'!D28",7,{"$f":"IF(SUM('1. Leverage Ratio'!D24:D27)='1. Leverage Ratio'!D28,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Total Off-Balance Sheet Exposures","In-schedule","SUM(S1.DP19:S1.DP22)=S1.SP33","SUM('1. Leverage Ratio'!D30:D33)='1. Leverage Ratio'!D34",8,{"$f":"IF(SUM('1. Leverage Ratio'!D30:D33)='1. Leverage Ratio'!D34,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Total Exposure Measure","In-schedule","S1.DP07+S1.DP13+S1.DP18+S1.DP23=S1.DP24","1. Leverage Ratio'!D14+'1. Leverage Ratio'!D22+'1. Leverage Ratio'!D28+'1. Leverage Ratio'!D34='1. Leverage Ratio'!D36",9,{"$f":"IF('1. Leverage Ratio'!D14+'1. Leverage Ratio'!D22+'1. Leverage Ratio'!D28+'1. Leverage Ratio'!D34='1. Leverage Ratio'!D36,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Tier 1 Capital after deductions","In-schedule","S1.DP25-S1.DP26=S1.DP27","1. Leverage Ratio'!D37-'1. Leverage Ratio'!D38='1. Leverage Ratio'!D39",10,{"$f":"IF('1. Leverage Ratio'!D37-'1. Leverage Ratio'!D38='1. Leverage Ratio'!D39,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Leverage Ratio","In-schedule","S1.DP27/S1.DP24=S1.DP28","1. Leverage Ratio'!D36=0,\"0\",'1. Leverage Ratio'!D39/'1. Leverage Ratio'!D36))='1. Leverage Ratio'!D40",11,{"$f":"IF((IF('1. Leverage Ratio'!D36=0,\"0\",'1. Leverage Ratio'!D39/'1. Leverage Ratio'!D36))='1. Leverage Ratio'!D40,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Schedule 2"]
["Validate Single derivative exposure not covered by an eligible netting contract, credit derivative contracts","In-schedule","S2.DP01+S2.DP03=S2.DP04","2. Derivative Exposures'!D4+'2. Derivative Exposures'!D6='2. Derivative Exposures'!D7",12,{"$f":"IF('2. Derivative Exposures'!D4+'2. Derivative Exposures'!D6='2. Derivative Exposures'!D7,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Exposure for netted derivatives, credit derivative contracts","In-schedule","S2.DP05+S2.DP07=S2.DP08","2. Derivative Exposures'!D9+'2. Derivative Exposures'!D11='2. Derivative Exposures'!D12",13,{"$f":"IF('2. Derivative Exposures'!D9+'2. Derivative Exposures'!D11='2. Derivative Exposures'!D12,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Net effective notional exposure for written credit derivative, credit derivative contracts ","In-schedule","S2.DP09-S2.DP10-S2.DP11=S2.DP12","2. Derivative Exposures'!D16-'2. Derivative Exposures'!D18-'2. Derivative Exposures'!D19='2. Derivative Exposures'!D20",14,{"$f":"IF('2. Derivative Exposures'!D16-'2. Derivative Exposures'!D18-'2. Derivative Exposures'!D19='2. Derivative Exposures'!D20,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Single derivative exposure not covered by an eligible netting contract, financial  derivative contracts","In-schedule","S2.DP13+S2.DP15=S2.DP16","2. Derivative Exposures'!E4+'2. Derivative Exposures'!E6='2. Derivative Exposures'!E7",15,{"$f":"IF('2. Derivative Exposures'!E4+'2. Derivative Exposures'!E6='2. Derivative Exposures'!E7,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Exposure for netted derivatives, financial derivative contracts","In-schedule","S2.DP17+S2.DP19=S2.DP20","2. Derivative Exposures'!E9+'2. Derivative Exposures'!E11='2. Derivative Exposures'!E12",16,{"$f":"IF('2. Derivative Exposures'!E9+'2. Derivative Exposures'!E11='2. Derivative Exposures'!E12,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate single derivative exposure not covered by an eligible netting contract - replacement cost, total contracts","In-schedule","S2.DP01+S2.DP13=S2.DP21","2. Derivative Exposures'!D4+'2. Derivative Exposures'!E4='2. Derivative Exposures'!F4",17,{"$f":"IF('2. Derivative Exposures'!D4+'2. Derivative Exposures'!E4='2. Derivative Exposures'!F4,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate single derivative exposure not covered by an eligible netting contract - notional amounts, total contracts","In-schedule","S2.DP02+S2.DP14=S2.DP22","2. Derivative Exposures'!D5+'2. Derivative Exposures'!E5='2. Derivative Exposures'!F5",18,{"$f":"IF('2. Derivative Exposures'!D5+'2. Derivative Exposures'!E5='2. Derivative Exposures'!F5,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate single derivative exposure not covered by an eligible netting contract - notional amounts PFE, total contracts","In-schedule","S2.DP03+S2.DP15=S2.DP23","2. Derivative Exposures'!D6+'2. Derivative Exposures'!E6='2. Derivative Exposures'!F6",19,{"$f":"IF('2. Derivative Exposures'!D6+'2. Derivative Exposures'!E6='2. Derivative Exposures'!F6,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate single derivative exposure not covered by an eligible netting contract - single derivative exposure, total contracts","In-schedule","S2.DP21+S2.DP23=S2.DP24","2. Derivative Exposures'!F4+'2. Derivative Exposures'!F6='2. Derivative Exposures'!F7",20,{"$f":"IF('2. Derivative Exposures'!F4+'2. Derivative Exposures'!F6='2. Derivative Exposures'!F7,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Derivative exposures covered by an eligible netting contract - replacement cost, total contracts","In-schedule","S2.DP05+S2.DP17=S2.DP25","2. Derivative Exposures'!D9+'2. Derivative Exposures'!E9='2. Derivative Exposures'!F9",21,{"$f":"IF('2. Derivative Exposures'!D9+'2. Derivative Exposures'!E9='2. Derivative Exposures'!F9,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Derivative exposures covered by an eligible netting contract - notional amounts, total contracts","In-schedule","S2.DP06+S2.DP18=S2.DP26","2. Derivative Exposures'!D10+'2. Derivative Exposures'!E10='2. Derivative Exposures'!F10",22,{"$f":"IF('2. Derivative Exposures'!D10+'2. Derivative Exposures'!E10='2. Derivative Exposures'!F10,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Derivative exposures covered by an eligible netting contract - notional amounts PFE, total contracts","In-schedule","S2.DP07+S2.DP1=S2.DP27","2. Derivative Exposures'!D11+'2. Derivative Exposures'!E11='2. Derivative Exposures'!F11",23,{"$f":"IF('2. Derivative Exposures'!D11+'2. Derivative Exposures'!E11='2. Derivative Exposures'!F11,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Derivative exposures covered by an eligible netting contract - exposure for netted derivatives, total contracts","In-schedule","S2.DP25+S2.DP27=S2.DP28","2. Derivative Exposures'!F9+'2. Derivative Exposures'!F11='2. Derivative Exposures'!F12",24,{"$f":"IF('2. Derivative Exposures'!F9+'2. Derivative Exposures'!F11='2. Derivative Exposures'!F12,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Schedule 3"]
["Validate Exposures with a 10% CCF","In-schedule","S3.DP02=S3.DP01","3.Off-Balance Sheet Exposures'!C4='3.Off-Balance Sheet Exposures'!C3",25,{"$f":"IF('3.Off-Balance Sheet Exposures'!C4='3.Off-Balance Sheet Exposures'!C3,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Exposures with a 20% CCF","In-schedule","SUM(S3.DP03:S3.DP04)=S3.DP05","SUM('3.Off-Balance Sheet Exposures'!C5:C6)='3.Off-Balance Sheet Exposures'!C7",26,{"$f":"IF(SUM('3.Off-Balance Sheet Exposures'!C5:C6)='3.Off-Balance Sheet Exposures'!C7,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Exposures with a 50% CCF","In-schedule","SUM(S3.DP06:S3.DP08)=S3.DP09","SUM('3.Off-Balance Sheet Exposures'!C8:C10)='3.Off-Balance Sheet Exposures'!C11",27,{"$f":"IF(SUM('3.Off-Balance Sheet Exposures'!C8:C10)='3.Off-Balance Sheet Exposures'!C11,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Exposures with a 100% CCF","In-schedule","SUM(S3.DP10:S3.DP16)=S3.DP17","SUM('3.Off-Balance Sheet Exposures'!C12:C18)='3.Off-Balance Sheet Exposures'!C19",28,{"$f":"IF(SUM('3.Off-Balance Sheet Exposures'!C12:C18)='3.Off-Balance Sheet Exposures'!C19,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Total Off Balance Sheet Exposures","In-schedule","S3.DP02+S3.DP05+S3.DP09+S3.DP17=S3.DP18","3.Off-Balance Sheet Exposures'!C4+'3.Off-Balance Sheet Exposures'!C7+'3.Off-Balance Sheet Exposures'!C11+'3.Off-Balance Sheet Exposures'!C19='3.Off-Balance Sheet Exposures'!C20",29,{"$f":"IF('3.Off-Balance Sheet Exposures'!C4+'3.Off-Balance Sheet Exposures'!C7+'3.Off-Balance Sheet Exposures'!C11+'3.Off-Balance Sheet Exposures'!C19='3.Off-Balance Sheet Exposures'!C20,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Unconditionally cancellable commitments - 10% CCF - Exposure after CCF","In-schedule","S3.DP01*10%=S3.DP19","3.Off-Balance Sheet Exposures'!C3*'3.Off-Balance Sheet Exposures'!D3='3.Off-Balance Sheet Exposures'!E3",30,{"$f":"IF('3.Off-Balance Sheet Exposures'!C3*'3.Off-Balance Sheet Exposures'!D3='3.Off-Balance Sheet Exposures'!E3,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Unconditionally cancellable commitments - 10% CCF - Expoures with a 10% CCF - Exposure after CCF","In-schedule","S3.DP20 = S3.DP10","3.Off-Balance Sheet Exposures'!E3='3.Off-Balance Sheet Exposures'!E4",31,{"$f":"IF('3.Off-Balance Sheet Exposures'!E3='3.Off-Balance Sheet Exposures'!E4,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Commitments with an original maturity of one year or less - 20% CCF - Exposure after CCF","In-schedule","S3.DP03*20%=S3.DP21","3.Off-Balance Sheet Exposures'!C5*'3.Off-Balance Sheet Exposures'!D5='3.Off-Balance Sheet Exposures'!E5",32,{"$f":"IF('3.Off-Balance Sheet Exposures'!C5*'3.Off-Balance Sheet Exposures'!D5='3.Off-Balance Sheet Exposures'!E5,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Short-term self-liquidating trade letters of credit - 20% CCF - Exposure after CCF","In-schedule","S3.DP04*20%=S3.DP22","3.Off-Balance Sheet Exposures'!C6*'3.Off-Balance Sheet Exposures'!D6='3.Off-Balance Sheet Exposures'!E6",33,{"$f":"IF('3.Off-Balance Sheet Exposures'!C6*'3.Off-Balance Sheet Exposures'!D6='3.Off-Balance Sheet Exposures'!E6,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Exposures with a 20% CCF - Exposure after CCF","In-schedule","SUM(S3.DP21:S3.DP22)=S3.DP23","SUM('3.Off-Balance Sheet Exposures'!E5:E6)='3.Off-Balance Sheet Exposures'!E7",34,{"$f":"IF(SUM('3.Off-Balance Sheet Exposures'!E5:E6)='3.Off-Balance Sheet Exposures'!E7,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Commitments with an original maturity over one year  - 50% CCF - Exposure after CCF","In-schedule","S3.DP06*50%=S3.DP24","3.Off-Balance Sheet Exposures'!C8*'3.Off-Balance Sheet Exposures'!D8='3.Off-Balance Sheet Exposures'!E8",35,{"$f":"IF('3.Off-Balance Sheet Exposures'!C8*'3.Off-Balance Sheet Exposures'!D8='3.Off-Balance Sheet Exposures'!E8,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Transaction-related contingent items - 50% CCF- Exposure after CCF","In-schedule","S3.DP07*50%=S3.DP25","3.Off-Balance Sheet Exposures'!C9*'3.Off-Balance Sheet Exposures'!D9='3.Off-Balance Sheet Exposures'!E9",36,{"$f":"IF('3.Off-Balance Sheet Exposures'!C9*'3.Off-Balance Sheet Exposures'!D9='3.Off-Balance Sheet Exposures'!E9,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Valdiate NIFs and RUFs - 50% CCF - Exposure after CCF","In-schedule","S3.DP08*50%=S3.DP26","3.Off-Balance Sheet Exposures'!C10*'3.Off-Balance Sheet Exposures'!D10='3.Off-Balance Sheet Exposures'!E10",37,{"$f":"IF('3.Off-Balance Sheet Exposures'!C10*'3.Off-Balance Sheet Exposures'!D10='3.Off-Balance Sheet Exposures'!E10,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Exposures with a 50% CCF - Exposure after CCF","In-schedule","SUM(S3.DP24:S3.DP26)=S3.DP27","SUM('3.Off-Balance Sheet Exposures'!E8:E10)='3.Off-Balance Sheet Exposures'!E11",38,{"$f":"IF(SUM('3.Off-Balance Sheet Exposures'!E8:E10)='3.Off-Balance Sheet Exposures'!E11,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Eligible servicer cash advance facilities - 10% CCF - Exposure after CCF","In-schedule","S3.DP10*100%=S3.DP28","3.Off-Balance Sheet Exposures'!C12*'3.Off-Balance Sheet Exposures'!D12='3.Off-Balance Sheet Exposures'!E12",39,{"$f":"IF('3.Off-Balance Sheet Exposures'!C12*'3.Off-Balance Sheet Exposures'!D12='3.Off-Balance Sheet Exposures'!E12,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Securitization liquidity facilities - 100% CCF - Exposure after CCF","In-schedule","S3.DP11*100%=S3.DP29","3.Off-Balance Sheet Exposures'!C13*'3.Off-Balance Sheet Exposures'!D13='3.Off-Balance Sheet Exposures'!E13",40,{"$f":"IF('3.Off-Balance Sheet Exposures'!C13*'3.Off-Balance Sheet Exposures'!D13='3.Off-Balance Sheet Exposures'!E13,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Other off balance sheet securitization exposures - 100% CCF - Exposure after CCF","In-schedule","S3.DP12*100%=S3.DP30","3.Off-Balance Sheet Exposures'!C14*'3.Off-Balance Sheet Exposures'!D14='3.Off-Balance Sheet Exposures'!E14",41,{"$f":"IF('3.Off-Balance Sheet Exposures'!C14*'3.Off-Balance Sheet Exposures'!D14='3.Off-Balance Sheet Exposures'!E14,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Direct credit substitutes - 100% CCF - Exposure after CCF","In-schedule","S3.DP13*100%=S3.DP31","3.Off-Balance Sheet Exposures'!C15*'3.Off-Balance Sheet Exposures'!D15='3.Off-Balance Sheet Exposures'!E15",42,{"$f":"IF('3.Off-Balance Sheet Exposures'!C15*'3.Off-Balance Sheet Exposures'!D15='3.Off-Balance Sheet Exposures'!E15,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Forward asset purchases - 100% CCF - Exposure after CCF","In-schedule","S3.DP14*100%=S3.DP32","3.Off-Balance Sheet Exposures'!C16*'3.Off-Balance Sheet Exposures'!D16='3.Off-Balance Sheet Exposures'!E16",43,{"$f":"IF('3.Off-Balance Sheet Exposures'!C16*'3.Off-Balance Sheet Exposures'!D16='3.Off-Balance Sheet Exposures'!E16,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Forward forward deposits - 100% CCF - Exposure after CCF","In-schedule","S3.DP15*100%=S3.DP33","3.Off-Balance Sheet Exposures'!C17*'3.Off-Balance Sheet Exposures'!D17='3.Off-Balance Sheet Exposures'!E17",44,{"$f":"IF('3.Off-Balance Sheet Exposures'!C17*'3.Off-Balance Sheet Exposures'!D17='3.Off-Balance Sheet Exposures'!E17,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Partly paid shares and securities - 100% CCF - Exposure after CCF","In-schedule","S3.DP16*100%=S3.DP24","3.Off-Balance Sheet Exposures'!C18*'3.Off-Balance Sheet Exposures'!D18='3.Off-Balance Sheet Exposures'!E18",45,{"$f":"IF('3.Off-Balance Sheet Exposures'!C18*'3.Off-Balance Sheet Exposures'!D18='3.Off-Balance Sheet Exposures'!E18,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Exposures with a 100% CCF - Exposure after CCF","In-schedule","SUM(S3.DP28:S3.DP34)=S3.DP35","SUM('3.Off-Balance Sheet Exposures'!E12:E18)='3.Off-Balance Sheet Exposures'!E19",46,{"$f":"IF(SUM('3.Off-Balance Sheet Exposures'!E12:E18)='3.Off-Balance Sheet Exposures'!E19,\"TRUE\",\"FALSE\")","v":"TRUE"}]
["Validate Total Off Balance Sheet exposures - Exposure after CCF","In-schedule","S3.DP20+S3.DP23+S3.DP27+S3.DP34=S3.DP35","3.Off-Balance Sheet Exposures'!E4+'3.Off-Balance Sheet Exposures'!E7+'3.Off-Balance Sheet Exposures'!E11+'3.Off-Balance Sheet Exposures'!E19='3.Off-Balance Sheet Exposures'!E20",47,{"$f":"IF('3.Off-Balance Sheet Exposures'!E4+'3.Off-Balance Sheet Exposures'!E7+'3.Off-Balance Sheet Exposures'!E11+'3.Off-Balance Sheet Exposures'!E19='3.Off-Balance Sheet Exposures'!E20,\"TRUE\",\"FALSE\")","v":"TRUE"}]

{"sheet":"Institution_Codes","index":8,"n_rows":35,"n_cols":9,"rows_kept":35,"cut":false,"hidden":true,"merged":[]}
["Select Institution","-",null,"Month",null,null,null,"Year"]
["ANSA Bank Limited","BBDA",null,"January",1,null,null,2023,23]
["ANSA Merchant Bank Limited","AMAL",null,"February",2,null,null,2024,24]
["ANSA Merchant Bank Limited Consolidated","AMAL_CONS",null,"March",3,null,null,2025,25]
["Caribbean Finance Company Limited","CFC",null,"April",4,null,null,2026,26]
["CIBC Caribbean Bank (Trinidad and Tobago) Limited","FCIB",null,"May",5,null,null,2027,27]
["Citibank (Trinidad & Tobago) Limited","CITI",null,"June",6,null,null,2028,28]
["Citicorp Merchant Bank Limited","CMBL",null,"July",7,null,null,2029,29]
["Citicorp Merchant Bank Limited Consolidated","CMBL_CONS",null,"August",8,null,null,2030,30]
["Development Finance Limited","DFL",null,"September",9,null,null,2031,31]
["Fidelity Finance and Leasing Company Limited","FFL",null,"October",10,null,null,2032,32]
["First Citizens Bank Limited","FCB",null,"November",11,null,null,2033,33]
["First Citizens Bank Limited Consolidated","FCB_CONS",null,"December",12,null,null,2034,34]
["First Citizens Depository Services Limited","FCMT",null,null,null,null,null,2035,35]
["First Citizens Group Financial Holdings Limited","FCB_HC",null,null,null,null,null,2036,36]
["First Citizens Trustee Services Limited","FCTS",null,null,null,null,null,2037,37]
["Guardian Group Trust Limited ","GAM",null,null,null,null,null,2038,38]
["Island Finance Trinidad & Tobago Limited","ISFL",null,null,null,null,null,2039,39]
["Jamaica Money Market Brokers (T&T) Limited","JMMB_HC",null,null,null,null,null,2040,40]
["JMMB Bank (T&T) Limited","ICBL",null,null,null,null,null,2041,41]
["JMMB Bank (T&T) Limited Consolidated","ICBL_CONS",null,null,null,null,null,2042,42]
["JMMB Express Finance (T&T) Limited","ITBM",null,null,null,null,null,2043,43]
["Massy Finance GFC Limited","GFC",null,null,null,null,null,2044,44]
["NCB Merchant Bank (Trinidad and Tobago) Limited","TFL",null,null,null,null,null,2045,45]
["RBC Financial (Caribbean) Limited","RBTT_CONS",null,null,null,null,null,2046,46]
["RBC Investment Management (Caribbean) Limited","RBAM",null,null,null,null,null,2047,47]
["RBC Merchant Bank (Caribbean) Limited","RMBF",null,null,null,null,null,2048,48]
["RBC Royal Bank (Trinidad & Tobago) Limited","RBTT",null,null,null,null,null,2049,49]
["RBC Trust (Trinidad & Tobago) Limited","RBT",null,null,null,null,null,2050,50]
["Republic Bank Limited","RBL"]
["Republic Bank Limited Consolidated","RBL_CONS"]
["Republic Financial Holdings Limited","RFHL"]
["Scotia Investments (Trinidad and Tobago) Limited","SITT"]
["Scotiabank Trinidad and Tobago Limited","BNS"]
["Scotiabank Trinidad and Tobago Limited Consolidated","BNS_CONS"]